{"id":4184,"date":"2015-11-22T15:41:10","date_gmt":"2015-11-22T14:41:10","guid":{"rendered":"https:\/\/sternreinigung.com\/de\/de\/?page_id=4184"},"modified":"2024-02-22T14:06:51","modified_gmt":"2024-02-22T13:06:51","slug":"test-seite","status":"publish","type":"page","link":"https:\/\/stern-dienstleistungen.de\/de\/","title":{"rendered":"Startseite"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text css=&#8220;.vc_custom_1452377644676{margin-top: -15px !important;margin-right: -35px !important;margin-left: -35px !important;}&#8220;]\n\t\t\t<!-- START Revolution Home Page 1 REVOLUTION SLIDER 6.6.20 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_1_1_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:transparent;padding:0;margin:0px auto;margin-top:0;margin-bottom:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_1_1\" style=\"\" data-version=\"6.6.20\">\n\t\t\t\t\t<rs-slides style=\"overflow: hidden; position: absolute;\">\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-7\" data-title=\"Slide\" data-thumb=\"\/\/sternreinigung.com\/de\/wp-content\/uploads\/2016\/01\/Fotolia_9939656_L__.jpg\" data-anim=\"r:0;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/stern-dienstleistungen.de\/de\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" title=\"Startseite\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/sternreinigung.com\/de\/wp-content\/uploads\/2016\/01\/Fotolia_9939656_L__.jpg\" data-parallax=\"off\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-7-layer-1\" \n\t\t\t\t\t\t\t\tclass=\"FatRounded\"\n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-color=\"rgba(255,255,255,1)\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:188px;y:m;yo:-150px;\"\n\t\t\t\t\t\t\t\tdata-text=\"s:22;l:26;a:center;\"\n\t\t\t\t\t\t\t\tdata-padding=\"t:20;r:22;b:20;l:25;\"\n\t\t\t\t\t\t\t\tdata-border=\"bor:50px,50px,50px,50px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"e:power2.inOut;st:2000;sp:2130;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;e:nothing;st:w;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"bgc:#000;bor:50px,50px,50px,50px;oX:50;oY:50;e:none;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:5;background-color:rgba(0,0,0,0.50);font-family:'Verdana', 'Geneva', 'sans-serif';cursor:pointer;\"\n\t\t\t\t\t\t\t>Der Natur zur Liebe, setzen wir nur umweltfreundliche Produkte ein. \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-6\" data-title=\"Slide\" data-thumb=\"\/\/sternreinigung.com\/de\/wp-content\/uploads\/2015\/11\/car1.jpg\" data-anim=\"r:0;\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/stern-dienstleistungen.de\/de\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"\" title=\"car1\" width=\"1241\" height=\"600\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/sternreinigung.com\/de\/wp-content\/uploads\/2015\/11\/car1.jpg\" data-parallax=\"off\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-1-slide-6-layer-1\" \n\t\t\t\t\t\t\t\tclass=\"FatRounded\"\n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-color=\"rgba(255,255,255,1)\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:-293px;y:m;yo:-170px;\"\n\t\t\t\t\t\t\t\tdata-text=\"s:22;l:26;a:center;\"\n\t\t\t\t\t\t\t\tdata-padding=\"t:20;r:22;b:20;l:25;\"\n\t\t\t\t\t\t\t\tdata-border=\"bor:50px,50px,50px,50px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"e:power2.inOut;st:1999.7158813477;sp:2130;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;e:nothing;st:8999.7158813477;\"\n\t\t\t\t\t\t\t\tdata-frame_hover=\"bgc:#000;bor:50px,50px,50px,50px;oX:50;oY:50;e:none;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:5;background-color:rgba(0,0,0,0.50);font-family:'Verdana', 'Geneva', 'sans-serif';cursor:pointer;\"\n\t\t\t\t\t\t\t>Wir liefern Qualit\u00e4t \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script>\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_1_1',rl:[1240,1024,778,480],el:[450,600,500,400],gw:[1240,1024,778,480],gh:[450,600,500,400],type:'standard',justify:'',layout:'fullwidth',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider11\"]!==undefined) {window.RS_MODULES.modules[\"revslider11\"].once = false;window.revapi1 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row row_id=&#8220;Home&#8220;][vc_column][vc_custom_heading text=&#8220;HERZLICH WILLKOMMEN!&#8220; font_container=&#8220;tag:h2|text_align:center&#8220; google_fonts=&#8220;font_family:Arimo%3Aregular%2Citalic%2C700%2C700italic|font_style:700%20bold%20regular%3A700%3Anormal&#8220;][vc_column_text]<\/p>\n<h4 style=\"text-align: center;\">Wir begr\u00fc\u00dfen Sie herzlich auf unserer Webseite und freuen uns \u00fcber Ihr Interesse.<\/h4>\n<p style=\"text-align: center;\">Unser Komplettservice bietet Ihnen Leistungen \u00fcber Geb\u00e4udemanagement, wie zum Beispiel Hausmeisterdienste, Winterdienste, Gr\u00fcnanlagenpflege und Geb\u00e4udereinigung \u00a0im Raum M\u00fcnchen an.<\/p>\n<p style=\"text-align: center;\">Gerne stellen wir bei fachlichen Fragen s\u00e4mtliche Informationen zur Verf\u00fcgung. Rufen Sie uns an unter der Telefon Nr.: 089\/ 45 56 43 80 an.<\/p>\n<h4 style=\"text-align: center;\">Die Zufriedenheit unserer Kunden ist unser oberstes Gebot<\/h4>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space css=&#8220;.vc_custom_1452378697031{margin-right: -35px !important;margin-left: -35px !important;background-color: #f2f2f2 !important;}&#8220;][\/vc_column][\/vc_row][vc_row row_id=&#8220;unternehmen&#8220;][vc_column][vc_custom_heading text=&#8220;UNTERNEHMEN&#8220; font_container=&#8220;tag:h2|text_align:left|color:%23cecece&#8220; google_fonts=&#8220;font_family:Arimo%3Aregular%2Citalic%2C700%2C700italic|font_style:700%20bold%20regular%3A700%3Anormal&#8220; css=&#8220;.vc_custom_1452635939901{margin-top: -30px !important;margin-right: -35px !important;margin-left: -35px !important;padding-top: 10px !important;padding-left: 35px !important;background-color: #a3a3a3 !important;}&#8220;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;1\/4&#8243;][vc_single_image image=&#8220;4304&#8243; img_size=&#8220;353&#215;255&#8243; style=&#8220;vc_box_rounded&#8220;][\/vc_column][vc_column width=&#8220;3\/4&#8243;][vc_column_text]Wir sind ein kompetenter, moderner und innovativer Dienstleister im und um den Bereich der Geb\u00e4udereinigung.<br \/>\nSeit dem Jahre 2008 bieten wir Sauberkeit und Zuverl\u00e4ssigkeit, verbunden mit einem exzellenten Preis-Leistungs-Verh\u00e4ltnis. Unser ganzer Service ist auf den Kunden und nicht nur auf h\u00f6chste Kundenzufriedenheit, sondern auf Kundenbegeisterung ausgerichtet.<\/p>\n<p>Unser qualitativ geschultes Personal erledigt die ihr \u00fcbertragenen Aufgaben gewissenhaft, zuverl\u00e4ssig und mit gr\u00f6\u00dfter Sorgfalt.<br \/>\nDadurch, aber auch vor allem durch unsere Flexibilit\u00e4t haben wir einen guten Ruf bei unseren gro\u00dfen und kleineren Auftraggebern erworben.<\/p>\n<ul>\n<li>Wir k\u00f6nnen sicherlich auch was f\u00fcr Sie tun!<\/li>\n<li>Kontaktieren Sie uns einfach!<\/li>\n<li>Wir erstellen Ihnen schnell, kostenlos und unverbindlich ein auf Ihr Anliegen zugeschnittenes Angebot!<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space css=&#8220;.vc_custom_1452378697031{margin-right: -35px !important;margin-left: -35px !important;background-color: #f2f2f2 !important;}&#8220;][\/vc_column][\/vc_row][vc_row row_id=&#8220;Leistungen&#8220;][vc_column][vc_custom_heading text=&#8220;LEISTUNGEN&#8220; font_container=&#8220;tag:h2|text_align:left|color:%23cecece&#8220; google_fonts=&#8220;font_family:Arimo%3Aregular%2Citalic%2C700%2C700italic|font_style:700%20bold%20regular%3A700%3Anormal&#8220; css=&#8220;.vc_custom_1452635973493{margin-top: -30px !important;margin-right: -35px !important;margin-left: -35px !important;padding-top: 10px !important;padding-left: 35px !important;background-color: #a3a3a3 !important;}&#8220;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;1\/6&#8243;][vc_single_image image=&#8220;4522&#8243; img_size=&#8220;171&#215;138&#8243;][\/vc_column][vc_column width=&#8220;5\/6&#8243;][vc_column_text]<\/p>\n<h3><strong>AUTOAUFBEREITUNG<\/strong><\/h3>\n<p><strong>WENN ES UM DIE PROFESSIONELLE PFLEGE IHRES FAHRZEUGS GEHT<\/strong><br \/>\nAn erster Stelle steht hier f\u00fcr uns die Qualit\u00e4t unser Arbeit und somit Ihre Zufriedenheit.<\/p>\n<ul>\n<li>Aussenreinigung<\/li>\n<li>Innenreinigung<\/li>\n<li>Nanoversiegelung<\/li>\n<li>Smart-Repair<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;1\/6&#8243;][vc_single_image image=&#8220;4364&#8243; img_size=&#8220;171&#215;138&#8243;][\/vc_column][vc_column width=&#8220;5\/6&#8243;][vc_column_text]<\/p>\n<h3><strong>GEB\u00c4UDEREINIGUNG<\/strong><\/h3>\n<ul>\n<li>Unterhaltsreinigung<\/li>\n<li>K\u00fcchenreinigung<\/li>\n<li>Glasreinigung<\/li>\n<li>Bauendreinigung aller Art<\/li>\n<li>Grundreinigung aller Art<\/li>\n<li>Bodenbeschichtungen<\/li>\n<li>Fassadenreinigung<\/li>\n<li>Hausmeisterservice<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;1\/6&#8243;][vc_single_image image=&#8220;4368&#8243; img_size=&#8220;171&#215;138&#8243;][\/vc_column][vc_column width=&#8220;5\/6&#8243;][vc_column_text]<\/p>\n<h3><strong>WINTERDIENST<\/strong><\/h3>\n<ul>\n<li>R\u00e4um- und Streudienst<\/li>\n<li>R\u00e4umfl\u00e4chen Kontrolle<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;1\/6&#8243;][vc_single_image image=&#8220;4370&#8243; img_size=&#8220;171&#215;138&#8243;][\/vc_column][vc_column width=&#8220;5\/6&#8243;][vc_column_text]<\/p>\n<h3><strong>SOMMERDIENST<\/strong><\/h3>\n<ul>\n<li>Gr\u00fcnfl\u00e4chenpflege<\/li>\n<li>Baum- und Heckenschnitt<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;1\/6&#8243;][vc_single_image image=&#8220;4349&#8243; img_size=&#8220;171&#215;138&#8243;][\/vc_column][vc_column width=&#8220;5\/6&#8243;][vc_column_text]<\/p>\n<h3><strong>ABBRUCH UND ENTSORGUNG<\/strong><\/h3>\n<p>Dank unserer langj\u00e4hrigen Erfahrungen und unserem gut geschulten Fachpersonal, sind wir in der Lage jede Aufgabe in diesem Segment mit besten Ergebnissen zu meistern. Sowohl vor, als auch w\u00e4hrend der Abbrucharbeiten werden hohe Sicherheitsregelungen gegen\u00fcber Mensch und Natur getroffen und eingehalten.<\/p>\n<p>Bei uns k\u00f6nnen Sie sich darauf verlassen, dass wir unsere Arbeiten mit h\u00f6chster Pr\u00e4zision erledigen.[\/vc_column_text][\/vc_column][\/vc_row][vc_row row_id=&#8220;Kontakt&#8220;][vc_column][vc_custom_heading text=&#8220;KONTAKT&#8220; font_container=&#8220;tag:h2|text_align:left|color:%23cecece&#8220; google_fonts=&#8220;font_family:Arimo%3Aregular%2Citalic%2C700%2C700italic|font_style:700%20bold%20regular%3A700%3Anormal&#8220; css=&#8220;.vc_custom_1452635993773{margin-top: -30px !important;margin-right: -35px !important;margin-left: -35px !important;padding-top: 10px !important;padding-left: 35px !important;background-color: #a3a3a3 !important;}&#8220;][\/vc_column][\/vc_row][vc_row el_class=&#8220;full_contact&#8220;][vc_column width=&#8220;4\/5&#8243; css=&#8220;.vc_custom_1609689644748{padding-right: -30px !important;}&#8220;][vc_column_text css=&#8220;.vc_custom_1609694327359{margin-top: -35px !important;}&#8220;]<iframe loading=\"lazy\" style=\"border: 0;\" tabindex=\"0\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d666.0754619795125!2d11.648125287790219!3d48.123858883594124!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x479ddffe2050f7b5%3A0x9c2d208512738be5!2sEibenstockstra%C3%9Fe%202%2C%2081825%20M%C3%BCnchen!5e1!3m2!1sde!2sde!4v1609694283300!5m2!1sde!2sde\" width=\"100%\" height=\"400\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" aria-hidden=\"false\"><\/iframe>[\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/5&#8243;][vc_column_text css=&#8220;.vc_custom_1708607510798{margin-left: 20px !important;}&#8220;]<\/p>\n<p class=\"wd-text-bold-color\">Hauptsitz:<\/p>\n<p>Stern Dienstleistungen<br \/>\nEibenstockstr. 2<br \/>\n81825 M\u00fcnchen<\/p>\n<p class=\"wd-text-bold-color\">Telefon:<\/p>\n<p>089\/ 45 56 43 80<\/p>\n<p class=\"wd-text-bold-color\">Mobil:<\/p>\n<p>0170\/ 285 96 35<\/p>\n<p class=\"wd-text-bold-color\">E-Mail<\/p>\n<p>info[a]stern-dienstleistungen.de<\/p>\n<p class=\"wd-text-bold-color\">Fax:<\/p>\n<p>089\/ 45 56 43 91[\/vc_column_text][\/vc_column][\/vc_row][vc_row row_id=&#8220;Impressum&#8220;][vc_column][vc_custom_heading text=&#8220;IMPRESSUM&#8220; font_container=&#8220;tag:h2|text_align:left|color:%23cecece&#8220; google_fonts=&#8220;font_family:Arimo%3Aregular%2Citalic%2C700%2C700italic|font_style:700%20bold%20regular%3A700%3Anormal&#8220; css=&#8220;.vc_custom_1452721762760{margin-top: -30px !important;margin-right: -35px !important;margin-left: -35px !important;padding-top: 10px !important;padding-left: 35px !important;background-color: #a3a3a3 !important;}&#8220;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;1\/3&#8243;][vc_column_text]Allgemeine Informationen<br \/>\nRechtliche Informationen<\/p>\n<p>Stern Dienstleistungen<br \/>\nEibenstockstr. 2<br \/>\n81825 M\u00fcnchen<\/p>\n<p>E-Mail: info[a]stern-dienstleistungen.de<br \/>\nInternet: www.stern-dienstleistungen.de<\/p>\n<p>Inhaber : Kemal Yildiz[\/vc_column_text][\/vc_column][vc_column width=&#8220;2\/3&#8243;][vc_column_text]<\/p>\n<h3>Rechtliche Hinweise<\/h3>\n<p>Die auf dieser Website an verschiedenen Stellen enthaltenen Links auf Angebote anderer Anbieter im Internet wurden sorgf\u00e4ltig ausgew\u00e4hlt und zusammengestellt. Diese hatten, soweit nach pflichtgem\u00e4\u00dfer Pr\u00fcfung ersichtlich, zum Zeitpunkt der Verlinkung keine rechtswidrigen, moralisch fragw\u00fcrdigen oder diffamierenden Inhalte. Nach \u00a7 6 Nr. 5 c TDG. Pflichtangaben nach \u00a7 6 Teledienstgesetz (TDG). Gesamte Texte, Grafiken und Bilder dieser Homepage unterliegen dem Copyright der Sternreinigung und sind evtl. durch Dritte urheberrechtlich gesch\u00fctzt.[\/vc_column_text][\/vc_column][\/vc_row][vc_row row_id=&#8220;Datenschutz&#8220;][vc_column][vc_custom_heading text=&#8220;DATENSCHUTZERKL\u00c4RUNG&#8220; font_container=&#8220;tag:h2|text_align:left|color:%23cecece&#8220; google_fonts=&#8220;font_family:Arimo%3Aregular%2Citalic%2C700%2C700italic|font_style:700%20bold%20regular%3A700%3Anormal&#8220; css=&#8220;.vc_custom_1527196236233{margin-top: -30px !important;margin-right: -35px !important;margin-left: -35px !important;padding-top: 10px !important;padding-left: 35px !important;background-color: #a3a3a3 !important;}&#8220;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h2>Datenschutzerkl\u00e4rung<\/h2>\n<p>Verantwortliche Stelle im Sinne der Datenschutzgesetze, insbesondere der EU-Datenschutzgrundverordnung (DSGVO), ist:<\/p>\n<p>Kemal Yildiz \/ Stern Dienstleistungen<br \/>\nEibenstockstr. 2<br \/>\n81825 M\u00fcnchen<br \/>\nE-Mailadresse: info[a]stern-dienstleistungen.de<br \/>\nInhaber: Kemal Yildiz<\/p>\n<h2>Ihre Betroffenenrechte<\/h2>\n<p>Unter den angegebenen Kontaktdaten unseres Datenschutzbeauftragten k\u00f6nnen Sie jederzeit folgende Rechte aus\u00fcben:<\/p>\n<ul>\n<li>Auskunft \u00fcber Ihre bei uns gespeicherten Daten und deren Verarbeitung,<\/li>\n<li>Berichtigung unrichtiger personenbezogener Daten,<\/li>\n<li>L\u00f6schung Ihrer bei uns gespeicherten Daten,<\/li>\n<li>Einschr\u00e4nkung der Datenverarbeitung, sofern wir Ihre Daten aufgrund gesetzlicher Pflichten noch nicht l\u00f6schen d\u00fcrfen,<\/li>\n<li>Widerspruch gegen die Verarbeitung Ihrer Daten bei uns und<\/li>\n<li>Daten\u00fcbertragbarkeit, sofern Sie in die Datenverarbeitung eingewilligt haben oder einen Vertrag mit uns abgeschlossen haben.<\/li>\n<\/ul>\n<p>Sofern Sie uns eine Einwilligung erteilt haben, k\u00f6nnen Sie diese jederzeit mit Wirkung f\u00fcr die Zukunft widerrufen.<\/p>\n<p>Sie k\u00f6nnen sich jederzeit mit einer Beschwerde an die f\u00fcr Sie zust\u00e4ndige Aufsichtsbeh\u00f6rde wenden. Ihre zust\u00e4ndige Aufsichtsbeh\u00f6rde richtet sich nach dem Bundesland Ihres Wohnsitzes, Ihrer Arbeit oder der mutma\u00dflichen Verletzung. Eine Liste der Aufsichtsbeh\u00f6rden (f\u00fcr den nicht\u00f6ffentlichen Bereich) mit Anschrift finden Sie unter: <a href=\"https:\/\/www.bfdi.bund.de\/DE\/Infothek\/Anschriften_Links\/anschriften_links-node.html\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.bfdi.bund.de\/DE\/Infothek\/Anschriften_Links\/anschriften_links-node.html<\/a>.<\/p>\n<h2>Zwecke der Datenverarbeitung durch die verantwortliche Stelle und Dritte<\/h2>\n<p>Wir verarbeiten Ihre personenbezogenen Daten nur zu den in dieser Datenschutzerkl\u00e4rung genannten Zwecken. Eine \u00dcbermittlung Ihrer pers\u00f6nlichen Daten an Dritte zu anderen als den genannten Zwecken findet nicht statt. Wir geben Ihre pers\u00f6nlichen Daten nur an Dritte weiter, wenn:<\/p>\n<ul>\n<li>Sie Ihre ausdr\u00fcckliche Einwilligung dazu erteilt haben,<\/li>\n<li>die Verarbeitung zur Abwicklung eines Vertrags mit Ihnen erforderlich ist,<\/li>\n<li>die Verarbeitung zur Erf\u00fcllung einer rechtlichen Verpflichtung erforderlich ist,<\/li>\n<\/ul>\n<p>die Verarbeitung zur Wahrung berechtigter Interessen erforderlich ist und kein Grund zur Annahme besteht, dass Sie ein \u00fcberwiegendes schutzw\u00fcrdiges Interesse an der Nichtweitergabe Ihrer Daten haben.<\/p>\n<h2>L\u00f6schung bzw. Sperrung der Daten<\/h2>\n<p>Wir halten uns an die Grunds\u00e4tze der Datenvermeidung und Datensparsamkeit. Wir speichern Ihre personenbezogenen Daten daher nur so lange, wie dies zur Erreichung der hier genannten Zwecke erforderlich ist oder wie es die vom Gesetzgeber vorgesehenen vielf\u00e4ltigen Speicherfristen vorsehen. Nach Fortfall des jeweiligen Zweckes bzw. Ablauf dieser Fristen werden die entsprechenden Daten routinem\u00e4\u00dfig und entsprechend den gesetzlichen Vorschriften gesperrt oder gel\u00f6scht.<\/p>\n<h2>Erfassung allgemeiner Informationen beim Besuch unserer Website<\/h2>\n<p>Wenn Sie auf unsere Website zugreifen, werden automatisch mittels eines Cookies Informationen allgemeiner Natur erfasst. Diese Informationen (Server-Logfiles) beinhalten etwa die Art des Webbrowsers, das verwendete Betriebssystem, den Domainnamen Ihres Internet-Service-Providers und \u00e4hnliches. Hierbei handelt es sich ausschlie\u00dflich um Informationen, welche keine R\u00fcckschl\u00fcsse auf Ihre Person zulassen.<\/p>\n<p>Diese Informationen sind technisch notwendig, um von Ihnen angeforderte Inhalte von Webseiten korrekt auszuliefern und fallen bei Nutzung des Internets zwingend an. Sie werden insbesondere zu folgenden Zwecken verarbeitet:<\/p>\n<ul>\n<li>Sicherstellung eines problemlosen Verbindungsaufbaus der Website,<\/li>\n<li>Sicherstellung einer reibungslosen Nutzung unserer Website,<\/li>\n<li>Auswertung der Systemsicherheit und -stabilit\u00e4t sowie<\/li>\n<li>zu weiteren administrativen Zwecken.<\/li>\n<\/ul>\n<p>Die Verarbeitung Ihrer personenbezogenen Daten basiert auf unserem berechtigten Interesse aus den vorgenannten Zwecken zur Datenerhebung. Wir verwenden Ihre Daten nicht, um R\u00fcckschl\u00fcsse auf Ihre Person zu ziehen. Empf\u00e4nger der Daten sind nur die verantwortliche Stelle und ggf. Auftragsverarbeiter.<\/p>\n<p>Anonyme Informationen dieser Art werden von uns ggfs. statistisch ausgewertet, um unseren Internetauftritt und die dahinterstehende Technik zu optimieren.<\/p>\n<h2>Cookies<\/h2>\n<p>Wie viele andere Webseiten verwenden wir auch so genannte \u201eCookies\u201c. Cookies sind kleine Textdateien, die von einem Websiteserver auf Ihre Festplatte \u00fcbertragen werden. Hierdurch erhalten wir automatisch bestimmte Daten wie z. B. IP-Adresse, verwendeter Browser, Betriebssystem und Ihre Verbindung zum Internet.<\/p>\n<p>Cookies k\u00f6nnen nicht verwendet werden, um Programme zu starten oder Viren auf einen Computer zu \u00fcbertragen. Anhand der in Cookies enthaltenen Informationen k\u00f6nnen wir Ihnen die Navigation erleichtern und die korrekte Anzeige unserer Webseiten erm\u00f6glichen.<\/p>\n<p>In keinem Fall werden die von uns erfassten Daten an Dritte weitergegeben oder ohne Ihre Einwilligung eine Verkn\u00fcpfung mit personenbezogenen Daten hergestellt.<\/p>\n<p>Nat\u00fcrlich k\u00f6nnen Sie unsere Website grunds\u00e4tzlich auch ohne Cookies betrachten. Internet-Browser sind regelm\u00e4\u00dfig so eingestellt, dass sie Cookies akzeptieren. Im Allgemeinen k\u00f6nnen Sie die Verwendung von Cookies jederzeit \u00fcber die Einstellungen Ihres Browsers deaktivieren. Bitte verwenden Sie die Hilfefunktionen Ihres Internetbrowsers, um zu erfahren, wie Sie diese Einstellungen \u00e4ndern k\u00f6nnen. Bitte beachten Sie, dass einzelne Funktionen unserer Website m\u00f6glicherweise nicht funktionieren, wenn Sie die Verwendung von Cookies deaktiviert haben.<\/p>\n<h2>Kontaktformular<\/h2>\n<p>Treten Sie bzgl. Fragen jeglicher Art per E-Mail oder Kontaktformular mit uns in Kontakt, erteilen Sie uns zum Zwecke der Kontaktaufnahme Ihre freiwillige Einwilligung. Hierf\u00fcr ist die Angabe einer validen E-Mail-Adresse erforderlich. Diese dient der Zuordnung der Anfrage und der anschlie\u00dfenden Beantwortung derselben. Die Angabe weiterer Daten ist optional. Die von Ihnen gemachten Angaben werden zum Zwecke der Bearbeitung der Anfrage sowie f\u00fcr m\u00f6gliche Anschlussfragen gespeichert. Nach Erledigung der von Ihnen gestellten Anfrage werden personenbezogene Daten automatisch gel\u00f6scht.<\/p>\n<h2>Verwendung von Scriptbibliotheken (Google Webfonts)<\/h2>\n<p>Um unsere Inhalte browser\u00fcbergreifend korrekt und grafisch ansprechend darzustellen, verwenden wir auf dieser Website Scriptbibliotheken und Schriftbibliotheken wie z. B. Google Webfonts (<a href=\"http:\/\/www.google.com\/webfonts\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.google.com\/webfonts\/<\/a>). Google Webfonts werden zur Vermeidung mehrfachen Ladens in den Cache Ihres Browsers \u00fcbertragen. Falls der Browser die Google Webfonts nicht unterst\u00fctzt oder den Zugriff unterbindet, werden Inhalte in einer Standardschrift angezeigt.<\/p>\n<p>Der Aufruf von Scriptbibliotheken oder Schriftbibliotheken l\u00f6st automatisch eine Verbindung zum Betreiber der Bibliothek aus. Dabei ist es theoretisch m\u00f6glich \u2013 aktuell allerdings auch unklar ob und ggf. zu welchen Zwecken \u2013 dass Betreiber entsprechender Bibliotheken Daten erheben.<\/p>\n<p>Die Datenschutzrichtlinie des Bibliothekbetreibers Google finden Sie hier: <a href=\"https:\/\/www.google.com\/policies\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.google.com\/policies\/privacy\/<\/a><\/p>\n<h2>Verwendung von Adobe Typekit<\/h2>\n<p>Wir setzen Adobe Typekit zur visuellen Gestaltung unserer Website ein. Typekit ist ein Dienst der Adobe Systems Software Ireland Ltd. der uns den Zugriff auf eine Schriftartenbibliothek gew\u00e4hrt. Zur Einbindung der von uns benutzten Schriftarten, muss Ihr Browser eine Verbindung zu einem Server von Adobe in den USA aufbauen und die f\u00fcr unsere Website ben\u00f6tigte Schriftart herunterladen. Adobe erh\u00e4lt hierdurch die Information, dass von Ihrer IP-Adresse unsere Website aufgerufen wurde. Weitere Informationen zu Adobe Typekit finden Sie in den Datenschutzhinweisen von Adobe, die Sie hier abrufen k\u00f6nnen: <a href=\"http:\/\/www.adobe.com\/privacy\/typekit.html\" target=\"_blank\" rel=\"noopener noreferrer\">www.adobe.com\/privacy\/typekit.html<\/a><\/p>\n<h2>Verwendung von Google Maps<\/h2>\n<p>Diese Webseite verwendet Google Maps API, um geographische Informationen visuell darzustellen. Bei der Nutzung von Google Maps werden von Google auch Daten \u00fcber die Nutzung der Kartenfunktionen durch Besucher erhoben, verarbeitet und genutzt. N\u00e4here Informationen \u00fcber die Datenverarbeitung durch Google k\u00f6nnen Sie <a href=\"http:\/\/www.google.com\/privacypolicy.html\" target=\"_blank\" rel=\"noopener noreferrer\">den Google-Datenschutzhinweisen<\/a> entnehmen. Dort k\u00f6nnen Sie im Datenschutzcenter auch Ihre pers\u00f6nlichen Datenschutz-Einstellungen ver\u00e4ndern.<\/p>\n<p>Ausf\u00fchrliche Anleitungen zur Verwaltung der eigenen Daten im Zusammenhang mit Google-Produkten<a href=\"http:\/\/www.dataliberation.org\/\" target=\"_blank\" rel=\"noopener noreferrer\"> finden Sie hier<\/a>.<\/p>\n<h2>Eingebettete YouTube-Videos<\/h2>\n<p>Auf einigen unserer Webseiten betten wir Youtube-Videos ein. Betreiber der entsprechenden Plugins ist die YouTube, LLC, 901 Cherry Ave., San Bruno, CA 94066, USA. Wenn Sie eine Seite mit dem YouTube-Plugin besuchen, wird eine Verbindung zu Servern von Youtube hergestellt. Dabei wird Youtube mitgeteilt, welche Seiten Sie besuchen. Wenn Sie in Ihrem Youtube-Account eingeloggt sind, kann Youtube Ihr Surfverhalten Ihnen pers\u00f6nlich zuzuordnen. Dies verhindern Sie, indem Sie sich vorher aus Ihrem Youtube-Account ausloggen.<\/p>\n<p>Wird ein Youtube-Video gestartet, setzt der Anbieter Cookies ein, die Hinweise \u00fcber das Nutzerverhalten sammeln.<\/p>\n<p>Wer das Speichern von Cookies f\u00fcr das Google-Ad-Programm deaktiviert hat, wird auch beim Anschauen von Youtube-Videos mit keinen solchen Cookies rechnen m\u00fcssen. Youtube legt aber auch in anderen Cookies nicht-personenbezogene Nutzungsinformationen ab. M\u00f6chten Sie dies verhindern, so m\u00fcssen Sie das Speichern von Cookies im Browser blockieren.<\/p>\n<p>Weitere Informationen zum Datenschutz bei \u201eYoutube\u201c finden Sie in der Datenschutzerkl\u00e4rung des Anbieters unter: <a href=\"https:\/\/www.google.de\/intl\/de\/policies\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.google.de\/intl\/de\/policies\/privacy\/ <\/a><\/p>\n<h2><strong>\u00c4nderung unserer Datenschutzbestimmungen<\/strong><\/h2>\n<p>Wir behalten uns vor, diese Datenschutzerkl\u00e4rung anzupassen, damit sie stets den aktuellen rechtlichen Anforderungen entspricht oder um \u00c4nderungen unserer Leistungen in der Datenschutzerkl\u00e4rung umzusetzen, z.B. bei der Einf\u00fchrung neuer Services. F\u00fcr Ihren erneuten Besuch gilt dann die neue Datenschutzerkl\u00e4rung.<\/p>\n<h2><strong>Fragen an den Datenschutzbeauftragten<\/strong><\/h2>\n<p>Wenn Sie Fragen zum Datenschutz haben, schreiben Sie uns bitte eine E-Mail oder wenden Sie sich direkt an die f\u00fcr den Datenschutz verantwortliche Person in unserer Organisation:<\/p>\n<p><em>Die Datenschutzerkl\u00e4rung wurde mit dem <\/em><a href=\"https:\/\/www.activemind.de\/datenschutz\/datenschutzhinweis-generator\/\" target=\"_blank\" rel=\"noopener noreferrer\"><em>Datenschutzerkl\u00e4rungs-Generator der activeMind AG erstellt<\/em><\/a><em>.<\/em>[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8220;full_contact&#8220;][vc_column width=&#8220;2\/3&#8243; el_class=&#8220;has-animation fade-in-from-left&#8220;][\/vc_column][vc_column width=&#8220;1\/3&#8243;][\/vc_column][\/vc_row][vc_row css=&#8220;.vc_custom_1458646499917{margin-right: -35px !important;margin-bottom: -50px !important;margin-left: -35px !important;padding-top: 20px !important;background-color: #e5e5e5 !important;}&#8220;][vc_column width=&#8220;1\/4&#8243;][vc_column_text css=&#8220;.vc_custom_1609695843217{padding-left: 25px !important;}&#8220;]<strong>Servicezeiten:<br \/>\n<\/strong> Telefon: 089\/ 45 56 43 80<br \/>\nMontag-Freitag:<br \/>\n8:30 &#8211; 17:00 Uhr[\/vc_column_text][vc_empty_space height=&#8220;12px&#8220;][\/vc_column][vc_column width=&#8220;1\/4&#8243;][\/vc_column][vc_column width=&#8220;1\/4&#8243;][\/vc_column][vc_column width=&#8220;1\/4&#8243;][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text css=&#8220;.vc_custom_1452377644676{margin-top: -15px !important;margin-right: -35px !important;margin-left: -35px !important;}&#8220;][\/vc_column_text][\/vc_column][\/vc_row][vc_row row_id=&#8220;Home&#8220;][vc_column][vc_custom_heading text=&#8220;HERZLICH WILLKOMMEN!&#8220; font_container=&#8220;tag:h2|text_align:center&#8220; google_fonts=&#8220;font_family:Arimo%3Aregular%2Citalic%2C700%2C700italic|font_style:700%20bold%20regular%3A700%3Anormal&#8220;][vc_column_text] Wir begr\u00fc\u00dfen Sie herzlich auf unserer Webseite und freuen uns \u00fcber Ihr Interesse. Unser Komplettservice bietet Ihnen Leistungen \u00fcber Geb\u00e4udemanagement, wie zum Beispiel Hausmeisterdienste, Winterdienste, Gr\u00fcnanlagenpflege und Geb\u00e4udereinigung \u00a0im Raum M\u00fcnchen an. Gerne stellen wir bei fachlichen Fragen s\u00e4mtliche Informationen zur Verf\u00fcgung. Rufen Sie uns an unter der Telefon Nr.: 089\/ 45 56 43 80 an. Die Zufriedenheit unserer Kunden ist unser oberstes Gebot [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space css=&#8220;.vc_custom_1452378697031{margin-right: -35px !important;margin-left: -35px !important;background-color: #f2f2f2 !important;}&#8220;][\/vc_column][\/vc_row][vc_row row_id=&#8220;unternehmen&#8220;][vc_column][vc_custom_heading text=&#8220;UNTERNEHMEN&#8220; font_container=&#8220;tag:h2|text_align:left|color:%23cecece&#8220; google_fonts=&#8220;font_family:Arimo%3Aregular%2Citalic%2C700%2C700italic|font_style:700%20bold%20regular%3A700%3Anormal&#8220; css=&#8220;.vc_custom_1452635939901{margin-top: -30px !important;margin-right: -35px !important;margin-left: -35px !important;padding-top: 10px !important;padding-left: 35px !important;background-color: #a3a3a3 !important;}&#8220;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;1\/4&#8243;][vc_single_image image=&#8220;4304&#8243; img_size=&#8220;353&#215;255&#8243; style=&#8220;vc_box_rounded&#8220;][\/vc_column][vc_column width=&#8220;3\/4&#8243;][vc_column_text]Wir sind ein kompetenter, moderner und innovativer Dienstleister im und um den Bereich der Geb\u00e4udereinigung. Seit dem Jahre 2008 bieten wir Sauberkeit und Zuverl\u00e4ssigkeit, verbunden mit einem exzellenten Preis-Leistungs-Verh\u00e4ltnis. Unser ganzer Service ist auf den Kunden und nicht nur auf h\u00f6chste Kundenzufriedenheit, sondern auf Kundenbegeisterung ausgerichtet. Unser qualitativ geschultes Personal erledigt die ihr \u00fcbertragenen Aufgaben gewissenhaft, zuverl\u00e4ssig und mit gr\u00f6\u00dfter Sorgfalt. Dadurch, aber auch vor allem durch unsere Flexibilit\u00e4t haben wir einen guten Ruf bei unseren gro\u00dfen und kleineren Auftraggebern erworben. Wir k\u00f6nnen sicherlich auch was f\u00fcr Sie tun! Kontaktieren Sie uns einfach! Wir erstellen Ihnen schnell, kostenlos und unverbindlich ein auf Ihr Anliegen zugeschnittenes Angebot! [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space css=&#8220;.vc_custom_1452378697031{margin-right: -35px !important;margin-left: -35px !important;background-color: #f2f2f2 !important;}&#8220;][\/vc_column][\/vc_row][vc_row row_id=&#8220;Leistungen&#8220;][vc_column][vc_custom_heading text=&#8220;LEISTUNGEN&#8220; font_container=&#8220;tag:h2|text_align:left|color:%23cecece&#8220; google_fonts=&#8220;font_family:Arimo%3Aregular%2Citalic%2C700%2C700italic|font_style:700%20bold%20regular%3A700%3Anormal&#8220; css=&#8220;.vc_custom_1452635973493{margin-top: -30px !important;margin-right: -35px !important;margin-left: -35px !important;padding-top: 10px !important;padding-left: 35px !important;background-color: #a3a3a3 !important;}&#8220;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;1\/6&#8243;][vc_single_image image=&#8220;4522&#8243; img_size=&#8220;171&#215;138&#8243;][\/vc_column][vc_column width=&#8220;5\/6&#8243;][vc_column_text] AUTOAUFBEREITUNG WENN ES UM DIE PROFESSIONELLE PFLEGE IHRES FAHRZEUGS GEHT An erster Stelle steht hier f\u00fcr uns die Qualit\u00e4t unser Arbeit und somit Ihre Zufriedenheit. Aussenreinigung Innenreinigung Nanoversiegelung Smart-Repair [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;1\/6&#8243;][vc_single_image image=&#8220;4364&#8243; img_size=&#8220;171&#215;138&#8243;][\/vc_column][vc_column width=&#8220;5\/6&#8243;][vc_column_text] GEB\u00c4UDEREINIGUNG Unterhaltsreinigung K\u00fcchenreinigung Glasreinigung Bauendreinigung aller Art Grundreinigung aller Art Bodenbeschichtungen Fassadenreinigung Hausmeisterservice [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;1\/6&#8243;][vc_single_image image=&#8220;4368&#8243; img_size=&#8220;171&#215;138&#8243;][\/vc_column][vc_column width=&#8220;5\/6&#8243;][vc_column_text] WINTERDIENST R\u00e4um- und Streudienst R\u00e4umfl\u00e4chen Kontrolle [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;1\/6&#8243;][vc_single_image image=&#8220;4370&#8243; img_size=&#8220;171&#215;138&#8243;][\/vc_column][vc_column width=&#8220;5\/6&#8243;][vc_column_text] SOMMERDIENST Gr\u00fcnfl\u00e4chenpflege Baum- und Heckenschnitt [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;1\/6&#8243;][vc_single_image image=&#8220;4349&#8243; img_size=&#8220;171&#215;138&#8243;][\/vc_column][vc_column width=&#8220;5\/6&#8243;][vc_column_text] ABBRUCH UND ENTSORGUNG Dank unserer langj\u00e4hrigen Erfahrungen und unserem gut geschulten Fachpersonal, sind wir in der Lage jede Aufgabe in diesem Segment mit besten Ergebnissen zu meistern. Sowohl vor, als auch w\u00e4hrend der Abbrucharbeiten werden hohe Sicherheitsregelungen gegen\u00fcber Mensch und Natur getroffen und eingehalten. Bei uns k\u00f6nnen Sie sich darauf verlassen, dass wir unsere Arbeiten mit h\u00f6chster Pr\u00e4zision erledigen.[\/vc_column_text][\/vc_column][\/vc_row][vc_row row_id=&#8220;Kontakt&#8220;][vc_column][vc_custom_heading text=&#8220;KONTAKT&#8220; font_container=&#8220;tag:h2|text_align:left|color:%23cecece&#8220; google_fonts=&#8220;font_family:Arimo%3Aregular%2Citalic%2C700%2C700italic|font_style:700%20bold%20regular%3A700%3Anormal&#8220; css=&#8220;.vc_custom_1452635993773{margin-top: -30px !important;margin-right: -35px !important;margin-left: -35px !important;padding-top: 10px !important;padding-left: 35px !important;background-color: #a3a3a3 !important;}&#8220;][\/vc_column][\/vc_row][vc_row el_class=&#8220;full_contact&#8220;][vc_column width=&#8220;4\/5&#8243; css=&#8220;.vc_custom_1609689644748{padding-right: -30px !important;}&#8220;][vc_column_text css=&#8220;.vc_custom_1609694327359{margin-top: -35px !important;}&#8220;][\/vc_column_text][\/vc_column][vc_column width=&#8220;1\/5&#8243;][vc_column_text css=&#8220;.vc_custom_1708607510798{margin-left: 20px !important;}&#8220;] Hauptsitz: Stern Dienstleistungen Eibenstockstr. 2 81825 M\u00fcnchen Telefon: 089\/ 45 56 43 80 Mobil: 0170\/ 285 96 35 E-Mail info[a]stern-dienstleistungen.de Fax: 089\/ 45 56 43 91[\/vc_column_text][\/vc_column][\/vc_row][vc_row row_id=&#8220;Impressum&#8220;][vc_column][vc_custom_heading text=&#8220;IMPRESSUM&#8220; font_container=&#8220;tag:h2|text_align:left|color:%23cecece&#8220; google_fonts=&#8220;font_family:Arimo%3Aregular%2Citalic%2C700%2C700italic|font_style:700%20bold%20regular%3A700%3Anormal&#8220; css=&#8220;.vc_custom_1452721762760{margin-top: -30px !important;margin-right: -35px !important;margin-left: -35px !important;padding-top: 10px !important;padding-left: 35px !important;background-color: #a3a3a3 !important;}&#8220;][\/vc_column][\/vc_row][vc_row][vc_column width=&#8220;1\/3&#8243;][vc_column_text]Allgemeine Informationen Rechtliche Informationen Stern<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"_links":{"self":[{"href":"https:\/\/stern-dienstleistungen.de\/de\/wp-json\/wp\/v2\/pages\/4184"}],"collection":[{"href":"https:\/\/stern-dienstleistungen.de\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/stern-dienstleistungen.de\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/stern-dienstleistungen.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stern-dienstleistungen.de\/de\/wp-json\/wp\/v2\/comments?post=4184"}],"version-history":[{"count":269,"href":"https:\/\/stern-dienstleistungen.de\/de\/wp-json\/wp\/v2\/pages\/4184\/revisions"}],"predecessor-version":[{"id":4555,"href":"https:\/\/stern-dienstleistungen.de\/de\/wp-json\/wp\/v2\/pages\/4184\/revisions\/4555"}],"wp:attachment":[{"href":"https:\/\/stern-dienstleistungen.de\/de\/wp-json\/wp\/v2\/media?parent=4184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}